{"id":1786,"count":98,"description":"In unserer Berufe-\u00dcbersicht finden Absolventen, Young Professionals und Berufst\u00e4tige Informationen zu zahlreichen Berufen. Vom Projektmanager \u00fcber den Online Marketing Manager bis zum Gesch\u00e4ftsf\u00fchrer. Informiere dich jetzt!","link":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/","name":"Berufe","slug":"berufe","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Berufe - Haufe Akademie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haufe-akademie.de\/blog\/berufe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Berufe - Haufe Akademie\" \/>\n<meta property=\"og:description\" content=\"In unserer Berufe-\u00dcbersicht finden Absolventen, Young Professionals und Berufst\u00e4tige Informationen zu zahlreichen Berufen. Vom Projektmanager \u00fcber den Online Marketing Manager bis zum Gesch\u00e4ftsf\u00fchrer. Informiere dich jetzt!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haufe-akademie.de\/blog\/berufe\/\" \/>\n<meta property=\"og:site_name\" content=\"Haufe Akademie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HaufeAkademie\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Berufe - Haufe Akademie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/","og_locale":"de_DE","og_type":"article","og_title":"Berufe - Haufe Akademie","og_description":"In unserer Berufe-\u00dcbersicht finden Absolventen, Young Professionals und Berufst\u00e4tige Informationen zu zahlreichen Berufen. Vom Projektmanager \u00fcber den Online Marketing Manager bis zum Gesch\u00e4ftsf\u00fchrer. Informiere dich jetzt!","og_url":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/","og_site_name":"Haufe Akademie","twitter_card":"summary_large_image","twitter_site":"@HaufeAkademie","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/","url":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/","name":"Berufe - Haufe Akademie","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.haufe-akademie.de\/blog\/berufe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haufe-akademie.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Berufe"}]},{"@type":"WebSite","@id":"https:\/\/www.haufe-akademie.de\/blog\/#website","url":"https:\/\/www.haufe-akademie.de\/blog\/","name":"Haufe Akademie","description":"","publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haufe-akademie.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization","name":"Haufe Akademie","url":"https:\/\/www.haufe-akademie.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","width":144,"height":144,"caption":"Haufe Akademie"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HaufeAkademie","https:\/\/x.com\/HaufeAkademie"]}]}},"_links":{"self":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/categories\/1786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts?categories=1786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}