{"id":11997,"date":"2018-09-27T15:38:58","date_gmt":"2018-09-27T13:38:58","guid":{"rendered":"https:\/\/www.haufe-akademie.de\/blog\/?p=11997"},"modified":"2021-09-24T10:12:53","modified_gmt":"2021-09-24T08:12:53","slug":"meine-team-und-fuehrungssituation-reflektieren","status":"publish","type":"post","link":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/","title":{"rendered":"Meine Team- und F\u00fchrungssituation reflektieren"},"content":{"rendered":"<p>Stellen Sie Ihre Teamsituation grafisch mit Ihnen grafisch vor:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11998 size-full\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_1.png\" alt=\"\" width=\"537\" height=\"129\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_1.png 537w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_1-150x36.png 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_1-300x72.png 300w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/p>\n<p>Wichtige Beziehungsmuster untereinander stellen Sie wie folgt dar:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11999 size-full\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_2.png\" alt=\"\" width=\"419\" height=\"137\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_2.png 419w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_2-150x49.png 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_2-300x98.png 300w\" sizes=\"auto, (max-width: 419px) 100vw, 419px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Formulieren Sie eine konkrete Fragestellung, die Sie hier zu Ihrer F\u00fchrungssituation kl\u00e4ren wollen:<\/p>\n<p>z.B.\u00a0\u00a0\u00a0 <em>Ich und mein Team: Wie kann ich Person M1 besser in mein Team integrieren?<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12000 size-full\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_3.png\" alt=\"\" width=\"439\" height=\"312\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_3.png 439w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_3-150x107.png 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/Meine-Team-und-Fuehrungssituation-reflektieren_3-300x213.png 300w\" sizes=\"auto, (max-width: 439px) 100vw, 439px\" \/><\/p>\n<h2>Mein Teambild<\/h2>\n<p>Meine Fragestellung, die ich hier kl\u00e4ren m\u00f6chte:<\/p>\n<h3><strong>Auswertung Teambildbesprechung:<\/strong><\/h3>\n<ol>\n<li>Was ist mir \u00fcber mein Team\/die einzelnen Mitarbeitenden klarer geworden?<\/li>\n<li>Was werde ich an meinem F\u00fchrungsverhalten \u00e4ndern? (Mehr tun, nicht mehr tun)<\/li>\n<li>Was konkret werde ich bis wann tun, um die F\u00fchrungssituation zu verbessern?<\/li>\n<li>\u00a0Was k\u00f6nnte mich davon abhalten?<\/li>\n<li>Von wem oder durch was k\u00f6nnte ich mir Unterst\u00fctzung dabei holen?<\/li>\n<\/ol>\n<div class=\"seminartipp leseprobe\">\r\n\t\r\n\t<h2>Leseprobe aus Seminarunterlage \"F\u00fchrungskompetenz f\u00fcr praxiserfahrene F\u00fchrungskr\u00e4fte\"<\/h2>\r\n\t<div class=\"content\">\r\n\t\t<p class=\"h3\">F\u00fchrungskompetenz f\u00fcr praxiserfahrene F\u00fchrungskr\u00e4fte  Neue Tools - Methoden - Praxiscoaching<\/p>\r\n\t\t<p>Als F\u00fchrungskraft haben Sie bereits praktische Erfahrungen in der Mitarbeiterf\u00fchrung gesammelt. Mit diesem Praxis-Training erweitern Sie gezielt Ihr Know-how zu aktuellen Methoden und Grundlagen der F\u00fchrung und lernen effektive F\u00fchrungstools kennen. Durch gezielten Einsatz dieser F\u00fchrungsinstrumente, aktuellem F\u00fchrungswissen, Erfahrung und Ihrer authentischen Pers\u00f6nlichkeit erzielen Sie langfristig hervorragende Resultate mit Ihren Mitarbeitern und steigern so Sicherheit, Wirksamkeit und Kompetenz in herausfordernden F\u00fchrungssituationen.<\/p>\n\r\n\t\t<div class=\"txt-right\">\r\n\t\t\t<a class=\"btn\" href=\"http:\/\/www.haufe-akademie.de\/5831\" onclick=\"target_econda_article()\">Zum Training: F\u00fchrungskompetenz f\u00fcr praxiserfahrene F\u00fchrungskr\u00e4fte<\/a>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"clear\"><\/div>\r\n\t\r\n<\/div><h2>Die Methode &#8222;kollegiale Beratung&#8220;<\/h2>\n<p>Ein typischer Ablauf w\u00e4re:<\/p>\n<ol>\n<li>Der\/die Fallgeber\/in stellt dar, wozu er\/sie den Rat der Anwesenden m\u00f6chte.<\/li>\n<li>Die anderen (Berater\/innen) stellen Verst\u00e4ndnisfragen, bis sie das Thema und die erforderlichen Zusammenh\u00e4nge ausreichend verstanden haben.<\/li>\n<li>Der\/die Fallgeber\/in pr\u00e4zisiert die Frage an die anderen. Den n\u00e4chsten Schritt h\u00f6rt er\/sie zu, ohne weitere Informationen zu geben, etwas zu erg\u00e4nzen oder klar zu stellen.<\/li>\n<li>\u201eGef\u00fchle und Impulse\u201d: Die Berater\/innen \u00e4u\u00dfern sich kurz, welche Gef\u00fchle und Impulse sie zu der geschilderten Situation haben.<\/li>\n<li>Komplimente\u201d: Die Berater\/innen benennen, was ihnen am Vorgehen, an der Haltung, oder von den Ideen und L\u00f6sungsans\u00e4tzen des\/der Fallgebers\/in gef\u00e4llt.<\/li>\n<li>Empfehlungen\u201d: Alle Berater\/innen geben Empfehlungen konkret auf die Fragestellung des\/der Fallgebers\/in. Zuvor notiert jede Person die Ideen auf einem Zettel. Damit erh\u00f6ht sich die Anzahl der Vorschl\u00e4ge.<\/li>\n<li>Der\/die Fallgeber\/in sagt, welche Gedanken, Aspekte und Empfehlungen ihm\/ihr wertvoll erscheinen und bedankt sich f\u00fcr die Anregungen und die Hilfe.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Stellen Sie Ihre Teamsituation grafisch mit Ihnen grafisch vor: Wichtige Beziehungsmuster untereinander stellen Sie wie folgt dar: &nbsp; Formulieren Sie eine konkrete Fragestellung, die Sie hier zu Ihrer F\u00fchrungssituation kl\u00e4ren wollen: z.B.\u00a0\u00a0\u00a0 Ich und mein Team: Wie kann ich Person M1 besser in mein Team integrieren? Mein Teambild Meine Fragestellung, die ich hier kl\u00e4ren m\u00f6chte:<\/p>\n<div class=\"pageReadMore\"><i class=\"fa fa-angle-right\"><\/i><a href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/\" title=\"Beitrag lesen\">Beitrag lesen<\/a><\/div>\n","protected":false},"author":30,"featured_media":21763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"no","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1054],"tags":[125,1755],"class_list":{"0":"post-11997","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-leseproben-fuehrung","8":"tag-fuehrungskompetenz","9":"tag-fuehrungssituation"},"acf":{"p_authors":[12071]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meine Team- und F\u00fchrungssituation reflektieren<\/title>\n<meta name=\"description\" content=\"Erfahren Sie in unserem Blobeitrag mehr \u00fcber neue Tools und Methoden f\u00fcr F\u00fchrungskr\u00e4fte. \u25ba Hierzu bieten wir Ihnen ein Training.\u2714\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meine Team- und F\u00fchrungssituation reflektieren\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie in unserem Blobeitrag mehr \u00fcber neue Tools und Methoden f\u00fcr F\u00fchrungskr\u00e4fte. \u25ba Hierzu bieten wir Ihnen ein Training.\u2714\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/\" \/>\n<meta property=\"og:site_name\" content=\"Haufe Akademie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HaufeAkademie\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-27T13:38:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-24T08:12:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/meine-team-und-fuehrungssituation-reflektieren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alois Summerer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:site\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alois Summerer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\" Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meine Team- und F\u00fchrungssituation reflektieren","description":"Erfahren Sie in unserem Blobeitrag mehr \u00fcber neue Tools und Methoden f\u00fcr F\u00fchrungskr\u00e4fte. \u25ba Hierzu bieten wir Ihnen ein Training.\u2714","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/","og_locale":"de_DE","og_type":"article","og_title":"Meine Team- und F\u00fchrungssituation reflektieren","og_description":"Erfahren Sie in unserem Blobeitrag mehr \u00fcber neue Tools und Methoden f\u00fcr F\u00fchrungskr\u00e4fte. \u25ba Hierzu bieten wir Ihnen ein Training.\u2714","og_url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/","og_site_name":"Haufe Akademie","article_publisher":"https:\/\/www.facebook.com\/HaufeAkademie","article_published_time":"2018-09-27T13:38:58+00:00","article_modified_time":"2021-09-24T08:12:53+00:00","og_image":[{"width":800,"height":384,"url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/meine-team-und-fuehrungssituation-reflektieren.jpg","type":"image\/jpeg"}],"author":"Alois Summerer","twitter_card":"summary_large_image","twitter_creator":"@HaufeAkademie","twitter_site":"@HaufeAkademie","twitter_misc":{"Verfasst von":"Alois Summerer","Gesch\u00e4tzte Lesezeit":" Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/#article","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/"},"author":{"name":"Angelika Joubert","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63"},"headline":"Meine Team- und F\u00fchrungssituation reflektieren","datePublished":"2018-09-27T13:38:58+00:00","dateModified":"2021-09-24T08:12:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/"},"wordCount":311,"publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/meine-team-und-fuehrungssituation-reflektieren.jpg","keywords":["f\u00fchrungskompetenz","F\u00fchrungssituation"],"articleSection":["Leseproben F\u00fchrung und Leadership"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/","url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/","name":"Meine Team- und F\u00fchrungssituation reflektieren","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/#primaryimage"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/meine-team-und-fuehrungssituation-reflektieren.jpg","datePublished":"2018-09-27T13:38:58+00:00","dateModified":"2021-09-24T08:12:53+00:00","description":"Erfahren Sie in unserem Blobeitrag mehr \u00fcber neue Tools und Methoden f\u00fcr F\u00fchrungskr\u00e4fte. \u25ba Hierzu bieten wir Ihnen ein Training.\u2714","breadcrumb":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/#primaryimage","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/meine-team-und-fuehrungssituation-reflektieren.jpg","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/meine-team-und-fuehrungssituation-reflektieren.jpg","width":800,"height":384},{"@type":"BreadcrumbList","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/meine-team-und-fuehrungssituation-reflektieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haufe-akademie.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Alle Beitr\u00e4ge","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/"},{"@type":"ListItem","position":3,"name":"F\u00fchrung und Leadership","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/"},{"@type":"ListItem","position":4,"name":"Leseproben F\u00fchrung und Leadership","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/fuehrung-und-leadership\/leseproben-fuehrung\/"},{"@type":"ListItem","position":5,"name":"Meine Team- und F\u00fchrungssituation reflektieren"}]},{"@type":"WebSite","@id":"https:\/\/www.haufe-akademie.de\/blog\/#website","url":"https:\/\/www.haufe-akademie.de\/blog\/","name":"Haufe Akademie","description":"","publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haufe-akademie.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization","name":"Haufe Akademie","url":"https:\/\/www.haufe-akademie.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","width":144,"height":144,"caption":"Haufe Akademie"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HaufeAkademie","https:\/\/x.com\/HaufeAkademie"]},{"@type":"Person","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63","name":"Angelika Joubert","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","caption":"Angelika Joubert"},"url":"https:\/\/www.haufe-akademie.de\/blog\/author\/angelika-joubert\/"}]}},"modified_by":"Angelika Joubert","jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2018\/09\/meine-team-und-fuehrungssituation-reflektieren.jpg","_links":{"self":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/11997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/comments?post=11997"}],"version-history":[{"count":5,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/11997\/revisions"}],"predecessor-version":[{"id":17147,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/11997\/revisions\/17147"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/autoren\/12071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media\/21763"}],"wp:attachment":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media?parent=11997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/categories?post=11997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/tags?post=11997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}