{"id":13830,"date":"2019-11-13T15:35:20","date_gmt":"2019-11-13T14:35:20","guid":{"rendered":"https:\/\/www.haufe-akademie.de\/blog\/?p=13830"},"modified":"2024-02-29T13:00:14","modified_gmt":"2024-02-29T12:00:14","slug":"compliance-risiken-erkennen-loesungen-finden","status":"publish","type":"post","link":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/","title":{"rendered":"Compliance Risiken erkennen \u2013 L\u00f6sungen finden"},"content":{"rendered":"<p>In den letzten Jahren sind viele deutsche Gro\u00dfkonzerne aufgrund von Verst\u00f6\u00dfen gegen Compliance-Richtlinien in die Schlagzeilen geraten. Doch wer davon ausgeht, dass nur gro\u00dfe Firmen m\u00f6glichen Compliance-Risiken ausgesetzt sind, liegt falsch. Jedes KMU in Deutschland kann Gefahr laufen, aufgrund mangelnder Rechtstreue oder fehlender ethischer Standards Schaden zu nehmen. Umso wichtiger ist es deshalb, sich die zentralen Compliance-Risiken bewusst zu machen, um ad\u00e4quate L\u00f6sungen zu finden.<\/p>\n<h2>Definition: Compliance und Compliance Manager:innen<\/h2>\n<p>Compliance schafft Mechanismen und Prozesse, die es Besch\u00e4ftigten eines Unternehmens erm\u00f6glichen, sich leichter an Recht und Gesetz zu halten. Plastisch dargestellt kann Compliance daher mit Leitplanken auf einer Autobahn verglichen werden. W\u00e4hrend diese Autofahrer:innen vor physischem Schaden sch\u00fctzen, bewahrt Compliance als Methodik das Unternehmen, F\u00fchrungskr\u00e4fte und andere Besch\u00e4ftigte vor finanziellen Sch\u00e4den. Dabei ist es nebens\u00e4chlich, ob diese Besch\u00e4ftigten \u201eauf der linken, mittleren oder rechten Spur der Autobahn fahren\u201c. Wichtig ist allein, dass sie sich in dem vom Recht vorgegebenen Rahmen, also \u201ezwischen den Leitplanken\u201c, bewegen. Drohen Besch\u00e4ftigte jedoch \u201egegen die Leitplanken zu fahren\u201c, greift Compliance ein und korrigiert. Anders ausgedr\u00fcckt kommt Compliance Manager:innen die Funktion als Schiedsrichter:in zu. Etablierte soziale Standards, das Regelwerk und deren Auftreten als eine souver\u00e4n \u201edas Spiel\u201c leitende Instanz wirken insoweit pr\u00e4ventiv. Bei Bedarf greifen Compliance Manager:innen aber auch repressiv ein, um die involvierten Personen wieder zu einem angemessenen Miteinander zu bewegen.<\/p>\n<p>Neben der Schadensvermeidung dient gute Compliance jedoch zugleich noch einem anderen Vorteil: Wenn Besch\u00e4ftigte im Unternehmen darauf vertrauen k\u00f6nnen, dass Arbeitsprozesse und Interne Richtlinien rechtskonform sind, k\u00f6nnen sie sich noch st\u00e4rker auf ihre eigene Kernkompetenz und ihre Kernaufgabe fokussieren. Compliance-Manager:innen halten als Dienstleister daher den Besch\u00e4ftigten den \u201eR\u00fccken frei\u201c und steigern auch dadurch den Mehrgewinn des Unternehmens.<\/p>\n<p><iframe loading=\"lazy\" id=\"js3q738108866\" title=\"3Q SDN\" src=\"https:\/\/playout.3qsdn.com\/embed\/17b1b477-7e32-42e4-a6b4-2f412f225ae9\" width=\"640px\" height=\"360px\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Was sind jedoch Compliance-Risiken?<\/h2>\n<p>Allgemein gesprochen sind Compliance-Risiken Risiken, die sich aus dem individuellen oder kollektiven Fehlverhalten von Mitarbeitenden, F\u00fchrungskr\u00e4ften oder dem Management ergeben k\u00f6nnen. In der Praxis werden diese Risiken auch als \u201eCorporate Misconduct\u201d bezeichnet.<\/p>\n<p>Compliance-Risiken machen sich auf verschiedenen Ebenen bemerkbar. So k\u00f6nnen Risiken bez\u00fcglich der Unternehmensreputation, der Haftung, des Rechts sowie der Wirtschaftlichkeit auftreten. Diese k\u00f6nnen wiederum ernsthafte finanzielle Sch\u00e4den zur Folge haben. Denn bei der Missachtung von Compliance-Richtlinien drohen Bu\u00dfgelder, Umsatzeinbu\u00dfen aufgrund von Reputationsverlust oder Schadensersatzforderungen. Mahnende Beispiele sind der Dieselskandal von VW oder die manipulierte Preisvergabe des ADAC. F\u00fchrungskr\u00e4fte und Verantwortliche f\u00fcr Verst\u00f6\u00dfe gegen die Compliance m\u00fcssen dar\u00fcber hinaus auf pers\u00f6nlicher Ebene mit rechtlichen Konsequenzen rechnen, die bis hin zu Haftstrafen reichen. Ein sehr prominentes Beispiel sind die Top-Manager des Audi-Konzerns, die im Zuge des Dieselskandals verhaftet wurden.<\/p>\n<p>Wie die Beispiele zeigen, lassen sich Compliance-Risiken ganz allgemein als Risiken verstehen, die aus Regelverst\u00f6\u00dfen hervorgehen. In der Unternehmenspraxis sind meist die Bereiche Korruption, Untreue, Betrug, Diebstahl, Kartelle oder Preisabsprachen betroffen. In gr\u00f6\u00dferen Unternehmen werden deshalb eigene Compliance-Abteilungen f\u00fcr diese Bereiche geschaffen.<\/p>\n<h2>Compliance-Risiken als Teil des Compliance-Systems<\/h2>\n<p>Unabh\u00e4ngig von der Unternehmensgr\u00f6\u00dfe sollte die Analyse der Compliance-Risiken immer Teil eines komplexen, ineinandergreifenden Compliance-Management-Systems (CMS) sein. So ist es prim\u00e4r die Aufgabe der Unternehmensf\u00fchrung, eine eigene Compliance-Kultur zu etablieren, aus welcher sich feste Compliance-Ziele ableiten lassen. Daraus ergeben sich, neben der Compliance-Risikoanalyse, wiederum m\u00f6gliche Compliance-Risiken.<\/p>\n<p>Im Rahmen des CMS k\u00f6nnen \u00fcber die Organisation der Compliance, das Umsetzen von Ma\u00dfnahmen als Teil des Compliance-Programms, die Compliance-Kommunikation sowie -Information und schlie\u00dflich die \u00dcberwachung von entsprechenden Richtlinien sowie der Compliance selbst notwendige Verbesserungen erzielt werden. Letztlich lassen sich dadurch bestehende Risiken minimieren und Sch\u00e4den verhindern.<\/p>\n<div class=\"seminartipp\">\r\n\t\r\n\t<div class=\"content-wrapper\">\r\n\t\t\r\n\t\t\t<div class=\"image\">\r\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"102\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/10\/Mann-neben-Tafel.jpg\" class=\"attachment-pod size-pod\" alt=\"\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/10\/Mann-neben-Tafel.jpg 230w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/10\/Mann-neben-Tafel-150x100.jpg 150w\" sizes=\"auto, (max-width: 153px) 100vw, 153px\" \/>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<div class=\"content\">\r\n\t\t\t<h2>Unsere Seminarempfehlung<\/h2>\r\n\t\t\t<p class=\"h3\">Interne Ermittlungen bei Compliance-Verst\u00f6\u00dfen<\/p>\r\n\t\t\t<p>Interne Ermittlungen bei Verdachtsf\u00e4llen stellen komplexe Herausforderungen f\u00fcr Compliance-Manager dar. Das Training beleuchtet zun\u00e4chst praxisnah, welche rechtlichen Rahmenbedingungen es zu beachten gilt. Dar\u00fcber hinaus lernen Sie, mit Unterst\u00fctzung eines erfahrenen Praktikers der Kriminalpolizei, wie Sie interne Ermittlungen bei Compliance-Ereignissen und -Verst\u00f6\u00dfen planen und welche vernehmungspsychologischen Gesichtspunkte Sie beachten sollten.<\/p>\n<br\/>\r\n\t\t\t<a class=\"btn\" href=\"https:\/\/www.haufe-akademie.de\/30382\" onclick=\"target_econda_article()\" data-track-style=\"clickbtn\" data-track-type=\"link\" data-track-action=\"recoprimary\" target=\"_blank\">Training: Interne Ermittlungen bei Compliance-Verst\u00f6\u00dfen<\/a>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t<div class=\"clear\"><\/div>\r\n\t\r\n<\/div><h2>Risikobereiche f\u00fcr Compliance-Vergehen<\/h2>\n<p>Vergehen gegen Compliance k\u00f6nnen sich auf ganz verschiedenen Ebenen abspielen. Folgende Bereiche sind insbesondere betroffen:<\/p>\n<ul>\n<li>Korruption\/ Betrug<\/li>\n<li>Datenschutz<\/li>\n<li>IT-Sicherheit<\/li>\n<li>Kartellrecht<\/li>\n<li>Marktmanipulation<\/li>\n<li>Geldw\u00e4sche<\/li>\n<li>Exportkontrolle<\/li>\n<li>Arbeitsrecht<\/li>\n<\/ul>\n<p>Im Rahmen des Compliance-Management-Systems sollten Unternehmen deshalb aktives Risikomanagement betreiben, um m\u00f6gliche Regelverst\u00f6\u00dfe zu verhindern.<\/p>\n<h2>Einstufung und Eingrenzung von Compliance-Risiken<\/h2>\n<p>Das Risikomanagement in Unternehmen kann durch Eingrenzen und Einstufen m\u00f6gliche Compliance-Verst\u00f6\u00dfe aufdecken oder pr\u00e4ventiv agieren. Compliance-Risiken lassen sich zum Beispiel auf unterschiedlichen Ebenen analysieren:<\/p>\n<ul>\n<li>\u00a0Risiken auf Produktebene: Was produzieren wir? Welche Besonderheiten haben unsere Produkte?<\/li>\n<li>L\u00e4nderrisiken: Mit welchen L\u00e4ndern machen wir Gesch\u00e4fte? Welche Regeln gelten dort? Wie ist es um die Rechtsstaatlichkeit bestellt? Gibt es bestehende Embargos?<\/li>\n<li>Branchenrisiken: In welcher Branche bewegen wir uns? Wie ist der Wettbewerb?<\/li>\n<li>Risiken auf Kundenebene: Wer sind unsere Kunden? Wer kauft unsere Produkte?<\/li>\n<li>Risiken bei Gesch\u00e4ftspartnern: Mit wem machen wir Gesch\u00e4fte? Von welchen Partnern sind unsere Gesch\u00e4fte abh\u00e4ngig?<\/li>\n<li>Rechtliche Risiken: Welche Gesetze oder Urteile m\u00fcssen beachtet werden?<\/li>\n<\/ul>\n<p>Durch die gezielte Pr\u00fcfung bestehender Regularien und der Umst\u00e4nde lassen sich bereits viele Compliance-Risiken eindeutig eingrenzen.<\/p>\n<h2>Ein Beispiel f\u00fcr einen L\u00f6sungsansatz bei personenbezogenen Risiken<\/h2>\n<p>Um Compliance-Risiken auf personenbezogener Ebene zu begegnen, k\u00f6nnen Unternehmen folgende Ma\u00dfnahmen treffen:<br \/>\nAbgleich von \u00f6ffentlichen Registern bei Gesch\u00e4ftspartnern<\/p>\n<ul>\n<li>Einstufung der Risiken in Abh\u00e4ngigkeit der gew\u00fcnschten Gesch\u00e4ftsbeziehung<\/li>\n<li>Kontrolle der Vertriebspartner:innen<\/li>\n<li>\u00dcberpr\u00fcfung der kompletten Supply-Chain inklusive Zulieferer:innen, Zwischenh\u00e4ndler:innen, Transaktionspartner:innen<\/li>\n<li>Kontrolle der Kreditw\u00fcrdigkeit von Vertragspartner:innen<\/li>\n<li>Anforderung von Unternehmensdaten von Gesch\u00e4ftspartner:innen<\/li>\n<li>Abgleich mit eigenen Datenbanken sowie externen Risikodatenbanken (Compliance Due Diligence)<\/li>\n<\/ul>\n<h2>3 Schritte im Umgang mit Compliance-Risiken<\/h2>\n<ol>\n<li>Risikovermeidung: Aufstellen von Regeln und Vorschriften; Implementierung einer Compliance-Kultur; regelm\u00e4\u00dfige Weiterbildungen und Compliance-Schulungen; Kontrolle und Dokumentation des Kenntnisstandes; Einrichtung eines Compliance-Management-Systems<\/li>\n<li>Risikofr\u00fcherkennung: Erstellen von kontinuierlichen Risikoanalysen; Einrichten einer Compliance-Due-Diligence Stelle f\u00fcr Whistleblower:innen; Identifizieren konkreter Verst\u00f6\u00dfe gegen die Compliance<\/li>\n<li>Reaktionen: Erheben von Sanktionen bei Verst\u00f6\u00dfen gegen Compliance; \u00dcberpr\u00fcfung des bestehenden CMS; Optimierung der Unternehmenskommunikation<\/li>\n<\/ol>\n<p><strong>Fazit:<\/strong> Es gibt nicht einen pauschalen L\u00f6sungsansatz f\u00fcr Compliance-Risiken<\/p>\n<p>Compliance-Risiken lassen sich nicht mit pauschalen Ma\u00dfnahmen reduzieren. Sowohl das Risiko selbst als auch die L\u00f6sungsans\u00e4tze sind immer spezifisch f\u00fcr jedes einzelne Unternehmen zu ermitteln. Dabei m\u00fcssen alle beteiligten Parteien ber\u00fccksichtigt werden, wie Kunden, M\u00e4rkte, Produkte, gesetzliche Regelungen oder Mitarbeiter. Schon bei dieser kurzen Aufz\u00e4hlung wird sichtbar, dass es DEN L\u00f6sungsansatz f\u00fcr Compliance-Risiken nicht gibt.<\/p>\n<p>Wichtig ist vielmehr, dass Unternehmen dazu \u00fcbergehen, eine eigene Compliance-Kultur einzurichten. Dabei k\u00f6nnen unternehmensweite Standards eingerichtet werden. Entscheidend ist dabei, dass F\u00fchrungskr\u00e4fte und das Management diese Standards nicht nur vorgeben, sondern selbst beispielhaft damit umgehen. Somit werden sie zu Vorbildern und Multiplikatoren des Compliance-Management-Systems.<\/p>\n<p>Kleinere Unternehmen haben die M\u00f6glichkeit, Compliance-Richtlinien auch schrittweise in den jeweiligen Abteilungen einzuf\u00fchren. Auf diese Weise kann das Unternehmen sich mit allen Beteiligten sukzessive weiterentwickeln. Compliance-Risiken werden letztlich dadurch entsch\u00e4rft, dass F\u00fchrungskr\u00e4fte, das Management sowie alle Mitarbeiterinnen und Mitarbeiter in ein CMS eingebunden werden und die damit verbundenen Leitlinien annehmen und verinnerlichen. Der wichtigste L\u00f6sungsansatz lautet somit: Compliance-Risiken werden durch Pr\u00e4vention, Aufkl\u00e4rung und Weiterbildung verringert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den letzten Jahren sind viele deutsche Gro\u00dfkonzerne aufgrund von Verst\u00f6\u00dfen gegen Compliance-Richtlinien in die Schlagzeilen geraten. Doch wer davon ausgeht, dass nur gro\u00dfe Firmen m\u00f6glichen Compliance-Risiken ausgesetzt sind, liegt falsch. Jedes KMU in Deutschland kann Gefahr laufen, aufgrund mangelnder Rechtstreue oder fehlender ethischer Standards Schaden zu nehmen. Umso wichtiger ist es deshalb, sich die<\/p>\n<div class=\"pageReadMore\"><i class=\"fa fa-angle-right\"><\/i><a href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/\" title=\"Beitrag lesen\">Beitrag lesen<\/a><\/div>\n","protected":false},"author":30,"featured_media":31170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"no","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[352],"tags":[1296,1297],"class_list":{"0":"post-13830","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-compliance","8":"tag-compliance-risiken","9":"tag-verstoesse"},"acf":{"p_authors":[5215]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compliance Risiken erkennen \u2013 L\u00f6sungen finden<\/title>\n<meta name=\"description\" content=\"Wer glaubt, dass nur gro\u00dfe Firmen Compliance-Risiken ausgesetzt sind, liegt falsch. \u25baWorauf KMU beim Thema Compliance achten sollten, lesen Sie im Blogbeitrag.\u2714\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compliance Risiken erkennen \u2013 L\u00f6sungen finden\" \/>\n<meta property=\"og:description\" content=\"Wer glaubt, dass nur gro\u00dfe Firmen Compliance-Risiken ausgesetzt sind, liegt falsch. \u25baWorauf KMU beim Thema Compliance achten sollten, lesen Sie im Blogbeitrag.\u2714\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/\" \/>\n<meta property=\"og:site_name\" content=\"Haufe Akademie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HaufeAkademie\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-13T14:35:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-29T12:00:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2019\/11\/compliance-risiken-erkennen-loesungen-finden.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rainer M. Grethel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:site\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer M. Grethel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\" Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compliance Risiken erkennen \u2013 L\u00f6sungen finden","description":"Wer glaubt, dass nur gro\u00dfe Firmen Compliance-Risiken ausgesetzt sind, liegt falsch. \u25baWorauf KMU beim Thema Compliance achten sollten, lesen Sie im Blogbeitrag.\u2714","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/","og_locale":"de_DE","og_type":"article","og_title":"Compliance Risiken erkennen \u2013 L\u00f6sungen finden","og_description":"Wer glaubt, dass nur gro\u00dfe Firmen Compliance-Risiken ausgesetzt sind, liegt falsch. \u25baWorauf KMU beim Thema Compliance achten sollten, lesen Sie im Blogbeitrag.\u2714","og_url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/","og_site_name":"Haufe Akademie","article_publisher":"https:\/\/www.facebook.com\/HaufeAkademie","article_published_time":"2019-11-13T14:35:20+00:00","article_modified_time":"2024-02-29T12:00:14+00:00","og_image":[{"width":800,"height":384,"url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2019\/11\/compliance-risiken-erkennen-loesungen-finden.jpg","type":"image\/jpeg"}],"author":"Rainer M. Grethel","twitter_card":"summary_large_image","twitter_creator":"@HaufeAkademie","twitter_site":"@HaufeAkademie","twitter_misc":{"Verfasst von":"Rainer M. Grethel","Gesch\u00e4tzte Lesezeit":" Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/#article","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/"},"author":{"name":"Angelika Joubert","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63"},"headline":"Compliance Risiken erkennen \u2013 L\u00f6sungen finden","datePublished":"2019-11-13T14:35:20+00:00","dateModified":"2024-02-29T12:00:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/"},"wordCount":1148,"publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2019\/11\/Compliance-risiken-erkennen.24.jpg","keywords":["Compliance-Risiken","Verst\u00f6\u00dfe"],"articleSection":["Compliance"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/","url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/","name":"Compliance Risiken erkennen \u2013 L\u00f6sungen finden","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/#primaryimage"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2019\/11\/Compliance-risiken-erkennen.24.jpg","datePublished":"2019-11-13T14:35:20+00:00","dateModified":"2024-02-29T12:00:14+00:00","description":"Wer glaubt, dass nur gro\u00dfe Firmen Compliance-Risiken ausgesetzt sind, liegt falsch. \u25baWorauf KMU beim Thema Compliance achten sollten, lesen Sie im Blogbeitrag.\u2714","breadcrumb":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/#primaryimage","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2019\/11\/Compliance-risiken-erkennen.24.jpg","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2019\/11\/Compliance-risiken-erkennen.24.jpg","width":800,"height":384},{"@type":"BreadcrumbList","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/compliance-risiken-erkennen-loesungen-finden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haufe-akademie.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Alle Beitr\u00e4ge","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/"},{"@type":"ListItem","position":3,"name":"Compliance","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/compliance\/"},{"@type":"ListItem","position":4,"name":"Compliance Risiken erkennen \u2013 L\u00f6sungen finden"}]},{"@type":"WebSite","@id":"https:\/\/www.haufe-akademie.de\/blog\/#website","url":"https:\/\/www.haufe-akademie.de\/blog\/","name":"Haufe Akademie","description":"","publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haufe-akademie.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization","name":"Haufe Akademie","url":"https:\/\/www.haufe-akademie.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","width":144,"height":144,"caption":"Haufe Akademie"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HaufeAkademie","https:\/\/x.com\/HaufeAkademie"]},{"@type":"Person","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63","name":"Angelika Joubert","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","caption":"Angelika Joubert"},"url":"https:\/\/www.haufe-akademie.de\/blog\/author\/angelika-joubert\/"}]}},"modified_by":"Angelika Joubert","jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2019\/11\/Compliance-risiken-erkennen.24.jpg","_links":{"self":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/13830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/comments?post=13830"}],"version-history":[{"count":6,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/13830\/revisions"}],"predecessor-version":[{"id":46585,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/13830\/revisions\/46585"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/autoren\/5215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media\/31170"}],"wp:attachment":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media?parent=13830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/categories?post=13830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/tags?post=13830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}