{"id":14918,"date":"2020-07-23T10:00:12","date_gmt":"2020-07-23T08:00:12","guid":{"rendered":"https:\/\/www.haufe-akademie.de\/blog\/?p=14918"},"modified":"2021-08-24T17:15:27","modified_gmt":"2021-08-24T15:15:27","slug":"mitarbeiterbindung-selektiv-oder-individuell-binden","status":"publish","type":"post","link":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/","title":{"rendered":"Mitarbeiterbindung: selektiv und individuell binden"},"content":{"rendered":"<p>Immer mehr Unternehmen ergreifen Ma\u00dfnahmen oder starten Programme, um die Mitarbeitendenbindung zu verbessern. Doch was ist unter Mitarbeitendenbindung zu verstehen? Welche Gr\u00fcnde sprechen daf\u00fcr? Wie wirkt eine starke Mitarbeitendenbindung? Welche Mitarbeitendenbindungsma\u00dfnahmen sind sinnvoll? Und wie l\u00e4sst sich der Faktor Mitarbeitendenbindung messen?<\/p>\n<h2>Mitarbeitendenbindung vor Recruiting<\/h2>\n<p>Wenn sich Unternehmen intensiv mit der Bindung ihrer Mitarbeitenden befassen, spielt die Senkung der ungewollten Fluktuation oftmals eine wichtige Rolle. H\u00e4ufig k\u00f6nnen Wegg\u00e4nge nur unter hohem Kosten- und Zeitaufwand gef\u00fcllt werden. Daher liegt es nahe, f\u00fcr eine feste Mitarbeitendenbindung zu sorgen.<\/p>\n<p>Zudem wurde bei der <a href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/wirksame-personalgewinnung-mit-der-zed-formel\/\">Personalgewinnung<\/a> die Erfahrung gemacht: Je mehr intern f\u00fcr bestimmte Mitarbeitenden-Zielgruppen getan wird, desto leichter ist es, \u00e4hnliche Bewerber:innen von au\u00dfen anzuziehen. So sind beispielsweise Unternehmen, die viel f\u00fcr ihre besonders leistungsstarken Mitarbeitenden tun, besonders attraktiv f\u00fcr wechselwillige High Performer.<\/p>\n<h2>Vorteile von Mitarbeitendenbindung<\/h2>\n<p>Einige Unternehmensleitungen stellen den Motivationsaspekt in den Vordergrund. Denn Mitarbeitende, die sich ihrem Unternehmen, ihren Arbeitsaufgaben, ihren Kollegen und ihrem Chef verbunden f\u00fchlen, engagieren sich st\u00e4rker als die, denen alle und alles egal ist. Mit der Intensivierung der Mitarbeitendenbindung verbinden sich daher in der Praxis drei Vorteile:<\/p>\n<ul>\n<li>Senken der ungewollten Fluktuation<\/li>\n<li>Steigern der Arbeitgeberattraktivit\u00e4t<\/li>\n<li>Verbessern der Performance<\/li>\n<\/ul>\n<h2>Was ist Mitarbeitendenbindung?<\/h2>\n<h5>&#8222;Mitarbeiterbindung bezeichnet den Grad des Zusammenhalts zwischen dem Mitarbeiter auf der einen Seite und der Organisation als Ganzes auf der anderen Seite.&#8220;<\/h5>\n<p>(Quelle: <a href=\"https:\/\/shop.haufe.de\/prod\/mitarbeiterbindung\"><u>Mitarbeiterbindung \u2013 inkl. Arbeitshilfen, Haufe Group<\/u><\/a>). Mitarbeitendenbindung setzt \u2013 wie jede Form der Bindung \u2013 sowohl eine:n Bindungspartner:in als auch Gegenseitigkeit voraus. In anderen Worten: Wer von seinen Mitarbeitenden Bindung verlangt, muss ihnen zuerst einmal selbst eine Bindungsbereitschaft entgegenbringen.<\/p>\n<p>Zum anderen weist die Definition darauf hin, dass Mitarbeitendenbindung keineswegs allein eine Aufgabe des Human Resources Bereichs ist. Auch F\u00fchrungskr\u00e4fte aller Ebenen bis hin zur Unternehmensleitung m\u00fcssen den Wert der Mitarbeitendenorientierung erkennen und leben, damit hohe Mitarbeitendenbindung entstehen kann.<\/p>\n<h2>Mitarbeitendenbindung steuern<\/h2>\n<p>Wem oder was k\u00f6nnen sich Mitarbeitende verbunden f\u00fchlen? Bedeutsam sind insbesondere vier Bindungspartnerschaften:<\/p>\n<ul>\n<li>Bindung zum Unternehmen (&#8222;Identifikation&#8220;)<\/li>\n<li>Bindung zu den Arbeitsaufgaben<\/li>\n<li>Bindung zu Team und Kolleg:innen<\/li>\n<li>Bindung zum:zur direkten Vorgesetzten<\/li>\n<\/ul>\n<p>Entscheidend ist zudem, welcher Art die Bindung ist. Man unterscheidet wiederum vier Bindungsformen:<\/p>\n<ul>\n<li>Kalkulatorische Mitarbeitendenbindung<\/li>\n<li>Habituelle Mitarbeitendenbindung<\/li>\n<li>Normative Mitarbeitendenbindung<\/li>\n<li>Affektive Mitarbeitendenbindung<\/li>\n<\/ul>\n<h2>Formen der Mitarbeitendenbindung<\/h2>\n<p>Die <strong>kalkulatorische Mitarbeitendenbindung<\/strong> basiert auf einem Vergleich der Aufwand-Nutzen-Relation der derzeitigen Besch\u00e4ftigung gegen\u00fcber sich bietenden Alternativen. Typische Ma\u00dfnahmen zur Steigerung der kalkulatorischen Mitarbeitendenbindung liegen im Bereich von Verg\u00fctung, Zuwendungen und <a href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/benefits\/\">Benefits<\/a>. Die <strong>habituelle Mitarbeitendenbindung<\/strong> beruht demgegen\u00fcber auf der menschlichen Tendenz, an Gewohntem festzuhalten. Wer sie intensivieren will, schafft Rituale. Ein gemeinsames Abteilungsfr\u00fchst\u00fcck an einem bestimmten Wochentag beispielsweise, das die Mitarbeitenden irgendwann gar nicht mehr missen m\u00f6chten.<\/p>\n<p><strong>Normative Mitarbeitendenbindung<\/strong> beruht prim\u00e4r auf Verpflichtungsgef\u00fchlen. Diese lassen sich z. B. durch Investitionen in die Weiterbildung der Mitarbeitenden steigern. Doch die mit Blick auf die drei erzielbaren Effekte der Mitarbeitendenbindung relevanteste Form ist die <strong>affektive Bindung<\/strong>. Sie beruht darauf, dass die beiden Bindungspartner:innen hinsichtlich ihrer Werte und Ziele weitgehend \u00fcbereinstimmen. Sinnvolle Ma\u00dfnahmen sorgen f\u00fcr hohe Werte-\u00dcbereinstimmung, etwa durch Beteiligung aller Mitarbeitenden an der Erstellung oder Aktualisierung von Leitwerten des Unternehmens. Und f\u00fcr \u00dcbereinstimmung der Ziele, beispielsweise mithilfe eines gut gemachten Zielvereinbarungssystems.<\/p>\n<h2>Mitarbeitendenbindung: Instrument mit 16 Tasten<\/h2>\n<p>So entstehen 4&#215;4=16 Felder, die die Mitarbeitendenbindung widerspiegeln. Wie relevant die Bindungsform und die Bindungspartnerschaft f\u00fcr die Gesamt-Bindung der Mitarbeitenden ist, h\u00e4ngt von dessen ganz individuellen Neigungen ab: Mancher ist besonders offen f\u00fcr affektive Vorgesetztenbindung, mancher eher f\u00fcr kalkulatorische Unternehmensbindung. Doch pr\u00e4sent sind immer alle vier Formen und alle vier Bezugsrichtungen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14919\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_16-Felder-300x146.jpg\" alt=\"\" width=\"692\" height=\"336\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_16-Felder-150x73@2x.jpg 300w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_16-Felder-150x73.jpg 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_16-Felder.jpg 800w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_16-Felder-300x146@2x.jpg 600w\" sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/><\/p>\n<p>Wer <strong>Mitarbeitendenbindung\u00a0messen<\/strong> m\u00f6chte, sollte die Daten daher auf Ebene der einzelnen Mitarbeitenden erheben. Wie hoch ist die Auspr\u00e4gung in dem jeweiligen Feld? Das kann durch Selbsteinsch\u00e4tzung mithilfe von Frageb\u00f6gen erfolgen oder \u2013 wie es auch im Bereich der Leistungsbeurteilung gemacht wird \u2013 durch Einsch\u00e4tzung der jeweiligen F\u00fchrungskraft. Letzteres macht dreifach Sinn:<\/p>\n<ol>\n<li>DerDie Vorgesetzte wird sich seiner Verantwortung f\u00fcr die Mitarbeitendenbindung bewusst.<\/li>\n<li>Er:Sie kann auch direkt individuell passende Ma\u00dfnahmen f\u00fcr bestimmte Felder entwickeln.<\/li>\n<li>Er:Sie st\u00e4rkt durch deren Umsetzung die Vorgesetztenbindung.<\/li>\n<\/ol>\n<h2>HR-seitige Mitarbeitendenbindungsma\u00dfnahmen<\/h2>\n<p>Auch HR kann erfolgreich aktiv werden. Dazu ist erforderlich, zun\u00e4chst ein strategisches Ziel-Arbeitgeberimage zu definieren. Wie soll das Unternehmen von Arbeitnehmenden gesehen werden: Familienfreundlich? Leistungsorientiert? Hip? Bodenst\u00e4ndig? Traditionell? Innovativ? Auf dieses Ziel-Arbeitgebendenimage werden alle Mitarbeitendenbindungsma\u00dfnahmen konsequent und deutlich sichtbar ausgerichtet.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14920\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_HR-seitige_Mitarbeiterbindungsmassnahmen-300x132.jpg\" alt=\"\" width=\"698\" height=\"307\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_HR-seitige_Mitarbeiterbindungsmassnahmen-150x66@2x.jpg 300w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_HR-seitige_Mitarbeiterbindungsmassnahmen-150x66.jpg 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_HR-seitige_Mitarbeiterbindungsmassnahmen.jpg 800w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_HR-seitige_Mitarbeiterbindungsmassnahmen-300x132@2x.jpg 600w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><\/p>\n<p>Keineswegs m\u00fcssen immer alle Mitarbeitenden eines Unternehmens in gleichem Ma\u00dfe von den Mitarbeitendenbindungsma\u00dfnahmen profitieren. M\u00f6glicherweise sollen gar nicht alle Mitarbeitenden gebunden werden. Oder manche etwas fester als andere. Es ist eine M\u00e4r, dass es den Betriebsfrieden st\u00f6rt, wenn manche qualitativ oder quantitativ mehr bekommen als andere. Es muss lediglich sinnvolle Kriterien geben, die die Intensit\u00e4t der Bindungsma\u00dfnahmen bestimmen. Dann wei\u00df jede:r Mitarbeiter:in, was er:sie tun muss, um ebenfalls von den besonderen Mitarbeitendenbindungsma\u00dfnahmen zu profitieren.<\/p>\n<h2>Mitarbeitendenbindung nach klaren Kriterien<\/h2>\n<p>Das Verfahren der Selektiven Individualisierten Mitarbeitendenbindung (SELIMAB) definiert vier Kriterien, die die Relevanz der Mitarbeitenden f\u00fcr den Erfolg des Unternehmens widerspiegeln:<\/p>\n<ol>\n<li>Kompetenzen und Qualifikationen (Potenzial)<\/li>\n<li>Leistung und Zielerreichung (Performance)<\/li>\n<li>Strategische Bedeutung der bekleideten Funktion<\/li>\n<li>Mangel an verf\u00fcgbaren Arbeitskr\u00e4ften f\u00fcr die bekleidete Funktion<\/li>\n<\/ol>\n<p>Anhand der Auspr\u00e4gung dieser vier Kriterien wird der Grad der angestrebten Bindung bestimmt. Und somit auch, welche Form und welches Ausma\u00df die Mitarbeitendenbindungsma\u00dfnahmen f\u00fcr die jeweiligen Mitarbeitenden-Gruppen annehmen sollten. Die beiden erstgenannten Kriterien sind auf die Person bezogen und k\u00f6nnen in einem Personalportfolio (Abbildung links) visualisiert werden. Die funktionsorientierten Kriterien 3 und 4 hingegen werden in einem <strong>Funktionsportfolio<\/strong> (Abb. rechts) dargestellt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14921\" src=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_links_rechts_800-300x170.jpg\" alt=\"\" width=\"736\" height=\"417\" srcset=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_links_rechts_800-150x85@2x.jpg 300w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_links_rechts_800-1024x582.jpg 1024w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_links_rechts_800-150x85.jpg 150w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_links_rechts_800-1536x873.jpg 1536w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_links_rechts_800.jpg 1771w, https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_Abb_links_rechts_800-300x170@2x.jpg 600w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/p>\n<p>Unter dem Gesichtspunkt der Wirtschaftlichkeit werden Unternehmen bei Mitarbeitenden, die \u00fcber ein hohes Potenzial verf\u00fcgen und eine beeindruckende Performance zeigen, besonders feste Mitarbeitendenbindung anstreben. Und diejenigen mit allen Mitteln an sich binden, die die strategisch bedeutsamen Funktionen besetzen und im Falle eines Weggangs kaum wiederzubesetzen w\u00e4ren.<\/p>\n<h2>Mitarbeitendenbindungsma\u00dfnahmen gezielt dosieren<\/h2>\n<p>Gerade erfolgskritische Schl\u00fcsselkr\u00e4fte k\u00f6nnen jedoch nicht durch 08\/15-Mitarbeitendenbindungsma\u00dfnahmen an Bord und motiviert gehalten werden. Sie sind nur durch Ma\u00dfnahmen zu begeistern, die individuell auf ihre Bed\u00fcrfnisse zugeschnitten sind. Daf\u00fcr muss die F\u00fchrungskraft den:die Mitarbeitende:n sehr gut kennen. Das kann nur der:die direkte Vorgesetzte leisten. Auf individueller Ebene ist Mitarbeitendenbindung eine F\u00fchrungsaufgabe, auf kollektiver Ebene eine Aufgabe des HR-Bereichs.<\/p>\n<p>Die Existenz- und Wettbewerbsf\u00e4higkeit aller Unternehmen und Organisationen h\u00e4ngt enorm davon ab, ob ihnen das Halten, Gewinnen und Motivieren ihrer Mitarbeitenden gelingt. Da ist es gut zu wissen, dass mit bindungsst\u00e4rkender Mitarbeitendenf\u00fchrung die wirksamste aller Ma\u00dfnahmen zugleich auch die kosteng\u00fcnstigste ist.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immer mehr Unternehmen ergreifen Ma\u00dfnahmen oder starten Programme, um die Mitarbeitendenbindung zu verbessern. Doch was ist unter Mitarbeitendenbindung zu verstehen? Welche Gr\u00fcnde sprechen daf\u00fcr? Wie wirkt eine starke Mitarbeitendenbindung? Welche Mitarbeitendenbindungsma\u00dfnahmen sind sinnvoll? Und wie l\u00e4sst sich der Faktor Mitarbeitendenbindung messen? Mitarbeitendenbindung vor Recruiting Wenn sich Unternehmen intensiv mit der Bindung ihrer Mitarbeitenden befassen, spielt<\/p>\n<div class=\"pageReadMore\"><i class=\"fa fa-angle-right\"><\/i><a href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/\" title=\"Beitrag lesen\">Beitrag lesen<\/a><\/div>\n","protected":false},"author":3,"featured_media":14922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"yes","_lmt_disable":"no","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[56,59],"tags":[126,934,195],"class_list":{"0":"post-14918","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-fuehrung-und-leadership","8":"category-personalmanagement","9":"tag-hr","10":"tag-mitarbeiterbindung","11":"tag-recruiting"},"acf":{"p_authors":[11589]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mitarbeiterbindung: selektiv und individuell binden<\/title>\n<meta name=\"description\" content=\"Was ist Mitarbeitendenbindung? Erfahren Sie hier mehr \u00fcber Vorteile, Formen der Mitarbeiterinnenbindung und Instrumenten zur Messung von Mitarbeiterbindung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mitarbeiterbindung: selektiv und individuell binden\" \/>\n<meta property=\"og:description\" content=\"Was ist Mitarbeitendenbindung? Erfahren Sie hier mehr \u00fcber Vorteile, Formen der Mitarbeiterinnenbindung und Instrumenten zur Messung von Mitarbeiterbindung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/\" \/>\n<meta property=\"og:site_name\" content=\"Haufe Akademie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HaufeAkademie\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-23T08:00:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-24T15:15:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_GettyImages-514712400_800x384.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gunther Wolf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:site\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gunther Wolf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\" Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mitarbeiterbindung: selektiv und individuell binden","description":"Was ist Mitarbeitendenbindung? Erfahren Sie hier mehr \u00fcber Vorteile, Formen der Mitarbeiterinnenbindung und Instrumenten zur Messung von Mitarbeiterbindung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/","og_locale":"de_DE","og_type":"article","og_title":"Mitarbeiterbindung: selektiv und individuell binden","og_description":"Was ist Mitarbeitendenbindung? Erfahren Sie hier mehr \u00fcber Vorteile, Formen der Mitarbeiterinnenbindung und Instrumenten zur Messung von Mitarbeiterbindung.","og_url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/","og_site_name":"Haufe Akademie","article_publisher":"https:\/\/www.facebook.com\/HaufeAkademie","article_published_time":"2020-07-23T08:00:12+00:00","article_modified_time":"2021-08-24T15:15:27+00:00","og_image":[{"width":800,"height":384,"url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_GettyImages-514712400_800x384.jpg","type":"image\/jpeg"}],"author":"Gunther Wolf","twitter_card":"summary_large_image","twitter_creator":"@HaufeAkademie","twitter_site":"@HaufeAkademie","twitter_misc":{"Verfasst von":"Gunther Wolf","Gesch\u00e4tzte Lesezeit":" Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/#article","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/"},"author":{"name":"Blog Team","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/88b50e9cc362db610ee4255c2b282434"},"headline":"Mitarbeiterbindung: selektiv und individuell binden","datePublished":"2020-07-23T08:00:12+00:00","dateModified":"2021-08-24T15:15:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/"},"wordCount":1109,"publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_GettyImages-514712400_800x384.jpg","keywords":["hr","Mitarbeiterbindung","Recruiting"],"articleSection":["F\u00fchrung und Leadership","Personalmanagement"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/","url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/","name":"Mitarbeiterbindung: selektiv und individuell binden","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/#primaryimage"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_GettyImages-514712400_800x384.jpg","datePublished":"2020-07-23T08:00:12+00:00","dateModified":"2021-08-24T15:15:27+00:00","description":"Was ist Mitarbeitendenbindung? Erfahren Sie hier mehr \u00fcber Vorteile, Formen der Mitarbeiterinnenbindung und Instrumenten zur Messung von Mitarbeiterbindung.","breadcrumb":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/#primaryimage","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_GettyImages-514712400_800x384.jpg","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_GettyImages-514712400_800x384.jpg","width":800,"height":384},{"@type":"BreadcrumbList","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/mitarbeiterbindung-selektiv-oder-individuell-binden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haufe-akademie.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Alle Beitr\u00e4ge","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/"},{"@type":"ListItem","position":3,"name":"Personalmanagement","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/personalmanagement\/"},{"@type":"ListItem","position":4,"name":"Mitarbeiterbindung: selektiv und individuell binden"}]},{"@type":"WebSite","@id":"https:\/\/www.haufe-akademie.de\/blog\/#website","url":"https:\/\/www.haufe-akademie.de\/blog\/","name":"Haufe Akademie","description":"","publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haufe-akademie.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization","name":"Haufe Akademie","url":"https:\/\/www.haufe-akademie.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","width":144,"height":144,"caption":"Haufe Akademie"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HaufeAkademie","https:\/\/x.com\/HaufeAkademie"]},{"@type":"Person","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/88b50e9cc362db610ee4255c2b282434","name":"Blog Team","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"http:\/\/haufe-akademie.de\/blog\/wp-content\/uploads\/2014\/05\/Blog-Team_avatar_1401199718.jpg","url":"http:\/\/haufe-akademie.de\/blog\/wp-content\/uploads\/2014\/05\/Blog-Team_avatar_1401199718.jpg","contentUrl":"http:\/\/haufe-akademie.de\/blog\/wp-content\/uploads\/2014\/05\/Blog-Team_avatar_1401199718.jpg","caption":"Blog Team"},"description":"Blog Team der Haufe Akademie.","url":"https:\/\/www.haufe-akademie.de\/blog\/author\/blog-team\/"}]}},"modified_by":"Claudia Riede","jetpack_featured_media_url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2020\/07\/Blog_Mitarbeiterbindung_GettyImages-514712400_800x384.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/14918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/comments?post=14918"}],"version-history":[{"count":6,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/14918\/revisions"}],"predecessor-version":[{"id":45690,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/14918\/revisions\/45690"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/autoren\/11589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media\/14922"}],"wp:attachment":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media?parent=14918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/categories?post=14918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/tags?post=14918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}