{"id":20080,"date":"2022-07-11T15:58:32","date_gmt":"2022-07-11T13:58:32","guid":{"rendered":"https:\/\/www.haufe-akademie.de\/blog\/?p=20080"},"modified":"2022-07-11T15:36:21","modified_gmt":"2022-07-11T13:36:21","slug":"4-spielregeln-fuer-flexible-zusammenarbeit-in-teams","status":"publish","type":"post","link":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/","title":{"rendered":"4 Spielregeln f\u00fcr flexible Zusammenarbeit im Team"},"content":{"rendered":"<p>Die Zukunft der Teamarbeit ist flexibel. Studien zeigen, dass der Trend zu 2-3 Tagen remote Arbeit geht. S\u00e4tze wie \u201eIch muss gleich meine Tochter abholen und 15 Minuten fr\u00fcher raus\u201d oder \u201eMein Mann hat unser B\u00fcro f\u00fcr einen Termin blockiert\u201d geh\u00f6ren heute zur Normalit\u00e4t vieler Teams.<\/p>\n<p>Flexible Zusammenarbeit bringt neben Chancen auch neue Herausforderungen mit sich. So ist es auf Distanz nicht so leicht, echten Teamgeist zu entwickeln. Die Grenze von Beruflichem und Privatem verschwimmt und kann zu \u00dcberlastung f\u00fchren. Zudem kommt es durch die meist schriftlich stattfindende Kommunikation schneller zu Missverst\u00e4ndnissen und Fehlinterpretationen, die wiederum zu schlechter Stimmung im Team f\u00fchren k\u00f6nnen. Deshalb stellen wir Ihnen 4 wichtige Spielregeln f\u00fcr erfolgreiche virtuelle Teamarbeit vor.<\/p>\n<h2>1. Team-Vereinbarungen \u00fcber Grundregeln der Zusammenarbeit<\/h2>\n<p>Die Organisation virtueller Zusammenarbeit ist deutlich komplexer als reine Pr\u00e4senzarbeit. F\u00fchrungskr\u00e4fte allein k\u00f6nnen kaum Regelungen finden, die den unterschiedlichen Bed\u00fcrfnissen und Arbeitsweisen gerecht werden. Umso wichtiger ist es, dass das Team selbst die Zusammenarbeit organisiert und den Rahmen gemeinsam kl\u00e4rt:<\/p>\n<ul>\n<li>Team-Erreichbarkeitszeiten: Was sind unsere Kernarbeitszeiten, zu denen wir in der Regel erreichbar sind? Ab wann ist Erreichbarkeit nicht mehr zu erwarten?<\/li>\n<li>Reaktionszeiten: Mit welchen Reaktionszeiten k\u00f6nnen Kund:innen und Kolleg:innen rechnen?<\/li>\n<li>Mediennutzung und Kommunikation: Was sind unsere prim\u00e4ren Kommunikationsmedien und zu welchen Anl\u00e4ssen\/Themen und bei welcher Dringlichkeit nutzen wir sie?<\/li>\n<li>Datenablage und Zugriff: Wo legen wir unsere Daten ab und wie sichern wir den Ortsunabh\u00e4ngigen Zugriff?<\/li>\n<\/ul>\n<p>Solche Vereinbarungen geben jedem Team-Mitglied Orientierung und auch die Erlaubnis, mal nicht erreichbar zu sein. Eine Visualisierung ist zudem f\u00fcr das <a href=\"\/blog\/themen\/personalentwicklung\/onboarding\/\">Onboarding<\/a> hilfreich, wenn neue Mitglieder in das flexible Team kommen. Vereinbarungen sollten regelm\u00e4\u00dfig gemeinsam \u00fcberpr\u00fcft und ggfs. angepasst werden, wenn Bed\u00fcrfnisse oder fachlicher Bedarf sich \u00e4ndern.<\/p>\n<h2>2. Den gr\u00f6\u00dften gemeinsamen Nenner finden<\/h2>\n<p>Zugegeben: Als wir angesichts der Pandemie gezwungen waren, innerhalb k\u00fcrzester Zeit unsere Zusammenarbeit in den virtuellen Raum zu \u00fcberf\u00fchren, gestaltete sich dies alles andere als reibungslos. Doch mittlerweile erkennen wir die Vorteile und Chancen des hybriden Arbeitsmodells. Wie w\u00e4re es also, wenn wir nicht nur genau so gut wie fr\u00fcher, sondern sogar besser flexibel zusammenarbeiten? Damit dies gelingen kann ist es wichtig, aus den unterschiedlichen Bed\u00fcrfnissen im Team den gr\u00f6\u00dften gemeinsamen Nenner zu finden.<\/p>\n<h3><u>Fragen, die bei der Kl\u00e4rung helfen k\u00f6nnen, sind:<\/u><\/h3>\n<ul>\n<li>Wie wichtig ist uns unsere zwischenmenschliche Beziehung und N\u00e4he?<\/li>\n<li>Wie schaffen wir m\u00f6glichst viel Stabilit\u00e4t in der Zusammenarbeit?<\/li>\n<li>Wie oft wollen wir uns mindestens treffen?<\/li>\n<li>Gibt es Tage, an denen wir alle vor Ort sein wollen?<\/li>\n<li>Zu welchen Anl\u00e4ssen wollen oder m\u00fcssen wir uns pers\u00f6nlich treffen?<\/li>\n<li>Wie gehen wir mit hybriden Treffen um?<\/li>\n<li>Bauen wir auf Regeln oder das Prinzip der Freiwilligkeit?<\/li>\n<\/ul>\n<p>Wie in einer guten Paarbeziehung gilt es auch hier, sich nicht auf Kompromisse einzulassen, sondern gemeinsam L\u00f6sungen zu finden, die f\u00fcr alle gewinnbringend sind. Hier hilft Mut, Neues auszuprobieren, um f\u00fcr das Team die beste Zusammenarbeitsform zu finden.<\/p>\n<h2>3. Routinen f\u00fcr effektive Kommunikation schaffen<\/h2>\n<p>Meetest du noch oder lebst schon? Eine Frage die angesichts einer explodierenden Anzahl an Meetings pro Tag an Relevanz gewinnt. Wenn sich ein Meeting an das n\u00e4chste reiht, ist das nicht nur anstrengend, sondern auch ineffektiv. Auch Studien belegen, dass unsere Konzentration in virtuellen Meetings nach sp\u00e4testens 75 Minuten deutlich nachl\u00e4sst. Um den Kalender zu entlasten kann die Etablierung von Routinen helfen: Gute Routinen zeichnen sich dadurch aus, dass sie<\/p>\n<ul>\n<li>regelm\u00e4\u00dfig wiederkehren<\/li>\n<li>immer den gleichen Ablauf haben<\/li>\n<li>ein konkretes Ergebnis\/ein konkreter Output damit verbunden ist<\/li>\n<\/ul>\n<p>Die Etablierung von Routinen, kann den Bedarf an kurzfristigen Meetings reduzieren und somit zu einem entspannteren Kalender f\u00fchren. Beispiele f\u00fcr Routinen sind zum Beispiel das \u201eDaily\u201d, ein t\u00e4glicher, 15 Minuten langer Austausch mit dem ganzen Team oder das agile Planungsmeeting \u201ePlanning\u201d. Eine \u201eMust-have\u201d Routine in hybriden Teams: die Retrospektive. Eine Routine, in der das Team die Zusammenarbeit reflektiert, kritische Themen offen anspricht und stetig an Verbesserungen arbeitet. Neben einer h\u00f6heren Zufriedenheit und Effektivit\u00e4t kann die Retrospektive das Vertrauen und Commitment im Team st\u00e4rken und zur Konfliktpr\u00e4vention beitragen.<\/p>\n<h2>4. Meetings effektiv gestalten<\/h2>\n<p>Auch f\u00fcr die effektive Gestaltung einzelner Meetings gibt es nat\u00fcrlich ein paar Spielregeln. Zum Beispiel: kein Meeting ohne Agenda. Zudem ist es sinnvoll, im Meeting konkrete Rollen zu vergeben, wie Moderator:in, Timekeer:in, Protokollant:in und Pr\u00e4sentator:in. Gerade in hybriden Meetings ist eine explizite Moderation unerl\u00e4sslich, damit virtuell Teilnehmende integriert sind.<\/p>\n<p>Rund um Meetings haben Organisationen und Teams in den vergangenen Monaten viel experimentiert. Hier ein paar \u201eHacks\u201d die Meetings verbessern k\u00f6nnen.<\/p>\n<h3><u>Kleine Meeting Hacks<\/u><\/h3>\n<ul>\n<li>Jedes Meeting startet mit einem Check-in, z.B. mit heytoday.com<\/li>\n<li>Reduzieren von Meetingzeiten (z.B. 50 statt 60 Minuten, 80 statt 90 usw.).<\/li>\n<li>Meetingfreie Tage oder Bl\u00f6cke im Team-Kalender.<\/li>\n<li>Die Teilnahme in den ersten Minuten jeden Meetings ist freiwillig und wird somit zum Raum f\u00fcr ungezwungen Austausch oder eine Pause.<\/li>\n<li>Klare Rollenverteilung f\u00fcr jedes Meeting (gerne rotierend).<\/li>\n<li>In der Agenda min. 10 % der Zeit f\u00fcr offene Themen freihalten.<\/li>\n<li>Reine Audiozeit in Meetings einbauen (entlastet das Gehirn).<\/li>\n<li>Jedes Team-Mitglied entscheidet selbst, an welchem Meeting er\/sie teilnimmt.<\/li>\n<li>Am Ende jeden Meetings Feedback fest etablieren, z.B. mit I like, I wish, um stetig an Verbesserungen zu arbeiten.<\/li>\n<\/ul>\n<p><strong>Fazit: <\/strong>Jedes Team ist anders und kann individuell f\u00fcr sich herausfinden, wie es am besten funktioniert und wie es arbeiten m\u00f6chte. Selbst gestaltete Rahmenbedingungen und Routinen geben jeder:m einzelnen Orientierung. \u00a0Wichtig f\u00fcr funktionierendes Teamwork (egal ob on- oder offline) ist das gegenseitige Vertrauen und Commitment \u2013 auch in der F\u00fchrung. Damit gelingt es dem Team, gemeinsam auch kritische Aspekte offen anzusprechen und die flexible Zusammenarbeit gemeinsam auf ein neues, h\u00f6heres Niveau zu heben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Zukunft der Teamarbeit ist flexibel. Studien zeigen, dass der Trend zu 2-3 Tagen remote Arbeit geht. S\u00e4tze wie \u201eIch muss gleich meine Tochter abholen und 15 Minuten fr\u00fcher raus\u201d oder \u201eMein Mann hat unser B\u00fcro f\u00fcr einen Termin blockiert\u201d geh\u00f6ren heute zur Normalit\u00e4t vieler Teams. Flexible Zusammenarbeit bringt neben Chancen auch neue Herausforderungen mit<\/p>\n<div class=\"pageReadMore\"><i class=\"fa fa-angle-right\"><\/i><a href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/\" title=\"Beitrag lesen\">Beitrag lesen<\/a><\/div>\n","protected":false},"author":30,"featured_media":20083,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"yes","_lmt_disable":"no","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[79],"tags":[1858,906,3411,3410,1144,2354,1038,3409,1859],"class_list":{"0":"post-20080","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-persoenliche-kompetenz","8":"tag-arbeiten-im-team","9":"tag-flexibilitaet","10":"tag-flexible-zusammenarbeit","11":"tag-hybridarbeit","12":"tag-kompetenzen","13":"tag-remote-arbeiten","14":"tag-teamwork","15":"tag-zukunft-der-teamarbeit","16":"tag-zusammenarbeit-in-teams"},"acf":{"p_authors":[14801]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 Spielregeln f\u00fcr flexible Zusammenarbeit im Team<\/title>\n<meta name=\"description\" content=\"Wie Sie Spielregeln festlegen k\u00f6nnen f\u00fcr die flexible Zusammenarbeit in Teams, verr\u00e4t unser Blogbeitrag. Hierzu bieten wir Seminare.\u2714\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 Spielregeln f\u00fcr flexible Zusammenarbeit im Team\" \/>\n<meta property=\"og:description\" content=\"Wie Sie Spielregeln festlegen k\u00f6nnen f\u00fcr die flexible Zusammenarbeit in Teams, verr\u00e4t unser Blogbeitrag. Hierzu bieten wir Seminare.\u2714\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/\" \/>\n<meta property=\"og:site_name\" content=\"Haufe Akademie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HaufeAkademie\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-11T13:58:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/07\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Henriette Hager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:site\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Henriette Hager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\" Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 Spielregeln f\u00fcr flexible Zusammenarbeit im Team","description":"Wie Sie Spielregeln festlegen k\u00f6nnen f\u00fcr die flexible Zusammenarbeit in Teams, verr\u00e4t unser Blogbeitrag. Hierzu bieten wir Seminare.\u2714","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/","og_locale":"de_DE","og_type":"article","og_title":"4 Spielregeln f\u00fcr flexible Zusammenarbeit im Team","og_description":"Wie Sie Spielregeln festlegen k\u00f6nnen f\u00fcr die flexible Zusammenarbeit in Teams, verr\u00e4t unser Blogbeitrag. Hierzu bieten wir Seminare.\u2714","og_url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/","og_site_name":"Haufe Akademie","article_publisher":"https:\/\/www.facebook.com\/HaufeAkademie","article_published_time":"2022-07-11T13:58:32+00:00","og_image":[{"width":800,"height":384,"url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/07\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams.jpg","type":"image\/jpeg"}],"author":"Henriette Hager","twitter_card":"summary_large_image","twitter_creator":"@HaufeAkademie","twitter_site":"@HaufeAkademie","twitter_misc":{"Verfasst von":"Henriette Hager","Gesch\u00e4tzte Lesezeit":" Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/#article","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/"},"author":{"name":"Angelika Joubert","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63"},"headline":"4 Spielregeln f\u00fcr flexible Zusammenarbeit im Team","datePublished":"2022-07-11T13:58:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/"},"wordCount":971,"publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/07\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams.jpg","keywords":["Arbeiten im Team","Flexibilit\u00e4t","flexible Zusammenarbeit","Hybridarbeit","Kompetenzen","remote arbeiten","Teamwork","Zukunft der Teamarbeit","Zusammenarbeit in Teams"],"articleSection":["Pers\u00f6nliche und Soziale Kompetenzen"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/","url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/","name":"4 Spielregeln f\u00fcr flexible Zusammenarbeit im Team","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/#primaryimage"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/07\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams.jpg","datePublished":"2022-07-11T13:58:32+00:00","description":"Wie Sie Spielregeln festlegen k\u00f6nnen f\u00fcr die flexible Zusammenarbeit in Teams, verr\u00e4t unser Blogbeitrag. Hierzu bieten wir Seminare.\u2714","breadcrumb":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/#primaryimage","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/07\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams.jpg","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/07\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams.jpg","width":800,"height":384},{"@type":"BreadcrumbList","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haufe-akademie.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Alle Beitr\u00e4ge","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/"},{"@type":"ListItem","position":3,"name":"Pers\u00f6nliche und Soziale Kompetenzen","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/persoenliche-kompetenz\/"},{"@type":"ListItem","position":4,"name":"4 Spielregeln f\u00fcr flexible Zusammenarbeit im Team"}]},{"@type":"WebSite","@id":"https:\/\/www.haufe-akademie.de\/blog\/#website","url":"https:\/\/www.haufe-akademie.de\/blog\/","name":"Haufe Akademie","description":"","publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haufe-akademie.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization","name":"Haufe Akademie","url":"https:\/\/www.haufe-akademie.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","width":144,"height":144,"caption":"Haufe Akademie"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HaufeAkademie","https:\/\/x.com\/HaufeAkademie"]},{"@type":"Person","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63","name":"Angelika Joubert","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","caption":"Angelika Joubert"},"url":"https:\/\/www.haufe-akademie.de\/blog\/author\/angelika-joubert\/"}]}},"modified_by":"Helena T\u00f6mke","jetpack_featured_media_url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2022\/07\/4-spielregeln-fuer-flexible-zusammenarbeit-in-teams.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/20080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/comments?post=20080"}],"version-history":[{"count":6,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/20080\/revisions"}],"predecessor-version":[{"id":45207,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/20080\/revisions\/45207"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/autoren\/14801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media\/20083"}],"wp:attachment":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media?parent=20080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/categories?post=20080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/tags?post=20080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}