{"id":7164,"date":"2016-04-29T10:51:54","date_gmt":"2016-04-29T08:51:54","guid":{"rendered":"https:\/\/www.haufe-akademie.de\/blog\/?p=7164"},"modified":"2020-04-15T08:53:41","modified_gmt":"2020-04-15T06:53:41","slug":"transportkosten-managen","status":"publish","type":"post","link":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/","title":{"rendered":"Transportkosten managen!"},"content":{"rendered":"<h2>Fokus Transportkosten: Kosten und Risiken vorausschauend managen<\/h2>\n<p>Transportrisiken sind einerseits nicht vorhersehbare, zuf\u00e4llige und unerwartete Ereignisse, die den zu transportierenden G\u00fctern Sch\u00e4den zuf\u00fcgen k\u00f6nnen, z. B. Unf\u00e4lle oder Diebstahl. Derartige Risiken sind im Normalfall versichert, was zumindest die Schadensfolgen begrenzt. Andere Transportrisiken sind mindestens ebenso bedeutend, lassen sich aber oft nicht versichern bzw. die Kosten hierf\u00fcr w\u00e4ren zu hoch. Zu nennen sind insbesondere diejenigen Kosten, deren Umfang und H\u00f6he durch Externe vorgegeben werden, etwa Infrastrukturabgaben oder auch die Entwicklung der Kraftstoffpreise. Dennoch gibt es M\u00f6glichkeiten, diese Kostenrisiken zu managen, sie zu begrenzen oder im besten Fall vollst\u00e4ndig zu eliminieren.<\/p>\n<h2>Maut- und Infrastrukturausgaben richtig verhandeln<\/h2>\n<p>Bei Vertragsverhandlungen sollten Mautkosten und andere Infrastrukturausgaben m\u00f6glichst separat von den eigentlichen Frachtkosten verhandelt werden. Hintergrund ist u. a., dass es auch relativ kurzfristig aufgrund politischer Entscheidungen zu \u00c4nderungen kommen kann, etwa der Ausweitung der Mautpflicht auf weitere Bundesstra\u00dfen oder Fahrzeuge von 7,5 bis 12 Tonnen. Ein weiterer Grund, der f\u00fcr eine separate Verhandlung spricht, ist, der Kundschaft transparent aufzuzeigen, wo und in welcher H\u00f6he Kosten entstehen, die man als Spediteur oder Logistikdienstleister nicht beeinflussen kann.<\/p>\n<p><strong>Praxis-Tipp<\/strong><br \/>\nEine separate Verhandlung mit gesondertem Ausweis von Maut- und Infrastrukturabgaben hat f\u00fcr beide Vertragsparteien auch den Vorteil, dass sofort erkennbar ist, wie sich der Preis f\u00fcr die eigentliche Transportleistung zusammensetzt und welche Kosten durch Dritte verursacht werden. Diskussionen \u00fcber unangemessene Preisanhebungen k\u00f6nnen Logistikdienstleister so im Keim ersticken.<\/p>\n<h2>Treibstoffkosten flexibel kalkulieren und anpassen<\/h2>\n<p>Auch die Kosten f\u00fcr Diesel und deren Entwicklung sind inzwischen nur noch schwer zu prognostizieren. Die Kosten k\u00f6nnen zum Teil sprunghaft steigen oder fallen. Wird mit festen Kosten gerechnet, kann es dazu kommen, dass bei kurzfristigen Schwankungen entweder der Spediteur draufzahlt, wenn die Kosten steigen. Bei sinkenden Kosten ist es der Kunde oder die Kundin. Um f\u00fcr beide Seiten eine sinnvolle L\u00f6sung zu finden, sollten Kraftstoffkosten mit einem Koeffizienten kalkuliert und verhandelt werden, der sich an Marktpreisindizes orientiert. Die aktuelle Preisentwicklung beim Treibstoff kann z. B. vom Bundesverband G\u00fcterkraftverkehr, Logistik und Entsorgung (BGL) in Erfahrung gebracht werden. So haben beide Vertragsparteien die M\u00f6glichkeit, ihre Kalkulationen stabil zu gestalten und k\u00f6nnen Kosten und Auszahlungen verl\u00e4sslich planen. In der Praxis hat sich eine monatliche Anpassung der Preise an die Kostenlage bew\u00e4hrt.<\/p>\n<p><strong>Praxis-Tipp<\/strong><br \/>\nAuf den ersten Blick hat nur der:die Verk\u00e4ufer:in bzw. der:die Spediteur:in etwas davon, wenn Kraftstoffkosten mit einem Koeffizienten oder einem anderen flexiblen Indikator verhandelt werden. Aber auch der:die K\u00e4ufer:in bzw. Kundin oder Kunde profitiert, da mit niedrigeren Kosten kalkuliert werden kann, wenn die Treibstoffkosten sinken.<\/p>\n<h2>Paketl\u00f6sungen als Chance<\/h2>\n<p>Sicher werden Logistikanbieter auch k\u00fcnftig versuchen, die Produktivit\u00e4t zu verbessern, um einen Teil der internen und externen Kostensteigerungen aufzufangen. Allerdings zeigt die Praxis, dass die Grenzen hier h\u00e4ufig fast erreicht sind. Ein Ansatz, dennoch Verbesserungen f\u00fcr beide Seiten zu erzielen, kann darin bestehen, dass man versucht, die Effizienz der Prozesse zu steigern. Das kann z. B. dadurch gelingen, m\u00f6glichst viele Transportleistungen mit und f\u00fcr einen bzw. wenige Kundinnen und Kunden zu \u00fcbernehmen. Durch die dann m\u00f6gliche engere Zusammenarbeit lassen sich vor allem die operativen Prozesse besser aufeinander abstimmen, u. a. auch mit einer automatisierten Frachtkostenplanung und -kontrolle. Beispielsweise wird es so erheblich einfacher, die Beauftragung, Abrechnung und Kontrolle von Auftr\u00e4gen aufeinander abzustimmen, die Auslastung des Laderaums und Fahrzeiten zu optimieren sowie Beschaffungs- und Lieferstrategien anzupassen. Zeit- und Arbeitsaufwand je Prozess lassen sich damit um bis zu 75 % reduzieren. In der Folge k\u00f6nnen die Kosten f\u00fcr Frachten oft \u00fcber 5 bis 8 % reduziert werden, so ein Ergebnis der Studie der Aberdeen Group\u00b9 .<\/p>\n<h2>Gemeinsame Kostenrechnungen f\u00fcr Logistiker und Kundschaft<\/h2>\n<p>Noch einen Schritt weiter k\u00f6nnen Unternehmen gehen, die ihre Zusammenarbeit \u00fcber alle Prozesse gemeinsam gestalten, indem sie auch ihre Kostenrechnungen aufeinander abstimmen. Beispielsweise k\u00f6nnen Entwicklungskosten (z. B. f\u00fcr die Entwicklung besserer Trackingsysteme, Energieeffizienzsteigerung oder Verbesserungen der Intralogistik) und Verdienstmargen mit festen Aufschl\u00e4gen versehen bei der Preisbildung ber\u00fccksichtigt werden. Die Vorteile f\u00fcr beide Seiten: gut planbare, auf l\u00e4ngere Sicht stabile Kosten bei transparenten Margen und M\u00f6glichkeiten, Verbesserungen zum Nutzen beider Parteien umzusetzen. Aufschl\u00e4ge und Margen sollten in Abst\u00e4nden von ca. einem Jahr \u00fcberpr\u00fcft und ggf. angepasst werden. Bei gr\u00f6\u00dferen Ver\u00e4nderungen w\u00e4hrend des Jahres, z. B. bei Kostensteigerungen durch Investitionen oder Personalanpassungen auch unterj\u00e4hrig.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fokus Transportkosten: Kosten und Risiken vorausschauend managen Transportrisiken sind einerseits nicht vorhersehbare, zuf\u00e4llige und unerwartete Ereignisse, die den zu transportierenden G\u00fctern Sch\u00e4den zuf\u00fcgen k\u00f6nnen, z. B. Unf\u00e4lle oder Diebstahl. Derartige Risiken sind im Normalfall versichert, was zumindest die Schadensfolgen begrenzt. Andere Transportrisiken sind mindestens ebenso bedeutend, lassen sich aber oft nicht versichern bzw. die Kosten<\/p>\n<div class=\"pageReadMore\"><i class=\"fa fa-angle-right\"><\/i><a href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/\" title=\"Beitrag lesen\">Beitrag lesen<\/a><\/div>\n","protected":false},"author":30,"featured_media":12870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"no","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1377],"tags":[3060,780,3062,3061,783,782,3059],"class_list":{"0":"post-7164","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-logistik-supply-chain-und-aussenhandel","8":"tag-frachtkostenplanung","9":"tag-kosten","10":"tag-kraftstoffkosten","11":"tag-mautkosten","12":"tag-transportkosten","13":"tag-transportlogistik","14":"tag-transportrisiken"},"acf":{"p_authors":[7166]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transportkosten managen!<\/title>\n<meta name=\"description\" content=\"Wie Sie die Kostenrisiken bei Transportkosten erfolgreich managen k\u00f6nnen, erfahren Sie im Blogbeitrag. \u25baHierzu bieten wir ein passendes Seminar.\u2714\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transportkosten managen!\" \/>\n<meta property=\"og:description\" content=\"Wie Sie die Kostenrisiken bei Transportkosten erfolgreich managen k\u00f6nnen, erfahren Sie im Blogbeitrag. \u25baHierzu bieten wir ein passendes Seminar.\u2714\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/\" \/>\n<meta property=\"og:site_name\" content=\"Haufe Akademie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HaufeAkademie\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-29T08:51:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-15T06:53:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/04\/Transportkosten_managen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Helmut Baumann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:site\" content=\"@HaufeAkademie\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helmut Baumann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\" Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transportkosten managen!","description":"Wie Sie die Kostenrisiken bei Transportkosten erfolgreich managen k\u00f6nnen, erfahren Sie im Blogbeitrag. \u25baHierzu bieten wir ein passendes Seminar.\u2714","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/","og_locale":"de_DE","og_type":"article","og_title":"Transportkosten managen!","og_description":"Wie Sie die Kostenrisiken bei Transportkosten erfolgreich managen k\u00f6nnen, erfahren Sie im Blogbeitrag. \u25baHierzu bieten wir ein passendes Seminar.\u2714","og_url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/","og_site_name":"Haufe Akademie","article_publisher":"https:\/\/www.facebook.com\/HaufeAkademie","article_published_time":"2016-04-29T08:51:54+00:00","article_modified_time":"2020-04-15T06:53:41+00:00","og_image":[{"width":800,"height":384,"url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/04\/Transportkosten_managen.jpg","type":"image\/jpeg"}],"author":"Helmut Baumann","twitter_card":"summary_large_image","twitter_creator":"@HaufeAkademie","twitter_site":"@HaufeAkademie","twitter_misc":{"Verfasst von":"Helmut Baumann","Gesch\u00e4tzte Lesezeit":" Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/#article","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/"},"author":{"name":"Angelika Joubert","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63"},"headline":"Transportkosten managen!","datePublished":"2016-04-29T08:51:54+00:00","dateModified":"2020-04-15T06:53:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/"},"wordCount":741,"publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/04\/Transportkosten_managen.jpg","keywords":["Frachtkostenplanung","Kosten","Kraftstoffkosten","Mautkosten","Transportkosten","Transportlogistik","Transportrisiken"],"articleSection":["Logistik, Supply Chain und Au\u00dfenhandel"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/","url":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/","name":"Transportkosten managen!","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/#primaryimage"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/04\/Transportkosten_managen.jpg","datePublished":"2016-04-29T08:51:54+00:00","dateModified":"2020-04-15T06:53:41+00:00","description":"Wie Sie die Kostenrisiken bei Transportkosten erfolgreich managen k\u00f6nnen, erfahren Sie im Blogbeitrag. \u25baHierzu bieten wir ein passendes Seminar.\u2714","breadcrumb":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/#primaryimage","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/04\/Transportkosten_managen.jpg","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/04\/Transportkosten_managen.jpg","width":800,"height":384,"caption":"Portrait of a smiling worker holding a digital tablet while standing in a large warehouse full of boxes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/transportkosten-managen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haufe-akademie.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Alle Beitr\u00e4ge","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/"},{"@type":"ListItem","position":3,"name":"Logistik, Supply Chain und Au\u00dfenhandel","item":"https:\/\/www.haufe-akademie.de\/blog\/themen\/logistik-supply-chain-und-aussenhandel\/"},{"@type":"ListItem","position":4,"name":"Transportkosten managen!"}]},{"@type":"WebSite","@id":"https:\/\/www.haufe-akademie.de\/blog\/#website","url":"https:\/\/www.haufe-akademie.de\/blog\/","name":"Haufe Akademie","description":"","publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haufe-akademie.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization","name":"Haufe Akademie","url":"https:\/\/www.haufe-akademie.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","width":144,"height":144,"caption":"Haufe Akademie"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HaufeAkademie","https:\/\/x.com\/HaufeAkademie"]},{"@type":"Person","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/person\/30fe9ce1c4f8c4f3f8529fe54c9add63","name":"Angelika Joubert","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca5cde36dbd822cfde94622c5d54ebff8792edae6d9a95ed59d43c4d174d38a5?s=96&d=blank&r=g","caption":"Angelika Joubert"},"url":"https:\/\/www.haufe-akademie.de\/blog\/author\/angelika-joubert\/"}]}},"modified_by":"Angelika Joubert","jetpack_featured_media_url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2016\/04\/Transportkosten_managen.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/7164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/comments?post=7164"}],"version-history":[{"count":5,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/7164\/revisions"}],"predecessor-version":[{"id":23289,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts\/7164\/revisions\/23289"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/autoren\/7166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media\/12870"}],"wp:attachment":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/media?parent=7164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/categories?post=7164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/tags?post=7164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}