{"id":4653,"count":1,"description":"","link":"https:\/\/www.haufe-akademie.de\/blog\/schlagwort\/einkaufsbedarf\/","name":"einkaufsbedarf","slug":"einkaufsbedarf","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>einkaufsbedarf - Haufe Akademie<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"einkaufsbedarf - Haufe Akademie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haufe-akademie.de\/blog\/schlagwort\/einkaufsbedarf\/\" \/>\n<meta property=\"og:site_name\" content=\"Haufe Akademie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HaufeAkademie\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"einkaufsbedarf - Haufe Akademie","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"einkaufsbedarf - Haufe Akademie","og_url":"https:\/\/www.haufe-akademie.de\/blog\/schlagwort\/einkaufsbedarf\/","og_site_name":"Haufe Akademie","twitter_card":"summary_large_image","twitter_site":"@HaufeAkademie","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.haufe-akademie.de\/blog\/schlagwort\/einkaufsbedarf\/","url":"https:\/\/www.haufe-akademie.de\/blog\/schlagwort\/einkaufsbedarf\/","name":"einkaufsbedarf - Haufe Akademie","isPartOf":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/schlagwort\/einkaufsbedarf\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.haufe-akademie.de\/blog\/schlagwort\/einkaufsbedarf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haufe-akademie.de\/blog\/"},{"@type":"ListItem","position":2,"name":"einkaufsbedarf"}]},{"@type":"WebSite","@id":"https:\/\/www.haufe-akademie.de\/blog\/#website","url":"https:\/\/www.haufe-akademie.de\/blog\/","name":"Haufe Akademie","description":"","publisher":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haufe-akademie.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.haufe-akademie.de\/blog\/#organization","name":"Haufe Akademie","url":"https:\/\/www.haufe-akademie.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","contentUrl":"https:\/\/www.haufe-akademie.de\/blog\/wp-content\/uploads\/2024\/06\/favicon_haufe.png","width":144,"height":144,"caption":"Haufe Akademie"},"image":{"@id":"https:\/\/www.haufe-akademie.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HaufeAkademie","https:\/\/x.com\/HaufeAkademie"]}]}},"_links":{"self":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/tags\/4653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.haufe-akademie.de\/blog\/wp-json\/wp\/v2\/posts?tags=4653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}